{"id":3720,"date":"2024-03-28T13:43:09","date_gmt":"2024-03-28T13:43:09","guid":{"rendered":"https:\/\/tgm.web4you.ai\/jobs\/maquinista-cnc\/"},"modified":"2024-08-21T18:37:16","modified_gmt":"2024-08-21T18:37:16","slug":"maquinista-cnc","status":"publish","type":"awsm_job_openings","link":"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/","title":{"rendered":"Maquinista CNC"},"content":{"rendered":"\n<p><strong>Descripci\u00f3n del puesto:<\/strong><\/p>\n\n<p>El empleado desempe\u00f1ar\u00e1 diversas funciones laborales, entre las que se incluyen las siguientes:<\/p>\n\n<ul class=\"wp-block-list\"><li>Operador de Fresadora CNC o Torno o Gundrill<\/li><li>Operador de m\u00e1quinas CNC y T\u00e9cnico de puesta a punto: incluir\u00e1 la puesta a punto y el seguimiento de 1 o m\u00e1s m\u00e1quinas de forma prioritaria. El t\u00e9cnico deber\u00e1 desplazarse de una m\u00e1quina a otra<\/li><li>Verificar las dimensiones de las piezas y productos mecanizados utilizando micr\u00f3metros, Vernier, calibres, medidores de altura, comparadores \u00f3pticos, m\u00e1quinas de medici\u00f3n de coordenadas (MMC) u otros instrumentos de medici\u00f3n de precisi\u00f3n.<\/li><li>Trabajar en un entorno de alta precisi\u00f3n y contribuir a mantener las especificaciones de dise\u00f1o y calidad.<\/li><li>Trabajar en equipo<\/li><li>Trabaja con las normas y pr\u00e1cticas TGM establecidas<\/li><li>Completa el trabajo del que eres responsable de forma puntual y productiva<\/li><\/ul>\n\n<p><strong>Otros datos:<\/strong><strong><\/strong><\/p>\n\n<ul class=\"wp-block-list\"><li>Puesto permanente a tiempo completo.<\/li><li>Rango salarial: Depende de la experiencia<\/li><li>Horas de trabajo: 40 horas de trabajo semanales m\u00e1s disponibilidad para hacer horas extraordinarias.<\/li><li>Prestaciones: Asistencia sanitaria ampliada, dental, RRSP, seguro de incapacidad a largo plazo y participaci\u00f3n en beneficios.<\/li><li>Un entorno estupendo con un enfoque individual profesional y un ambiente agradable.<\/li><\/ul>\n\n<p><strong>Cualificaciones:<\/strong><\/p>\n\n<ul class=\"wp-block-list\"><li>Se requiere el t\u00edtulo de Diplomado o Licenciado.<\/li><li>2 a\u00f1os de experiencia en Mecanizado CNC.<\/li><li>Capacidad mec\u00e1nica y comprensi\u00f3n de los principios de ingenier\u00eda.<\/li><li>Capacidad multitarea, manejar varias m\u00e1quinas a la vez.<\/li><li>Comprensi\u00f3n y experiencia con herramientas vivas.<\/li><li>Debe ser capaz de leer, escribir y comunicarse en ingl\u00e9s.<\/li><li>Capacidad para trabajar tanto en equipo como de forma independiente.<\/li><li>Capacidad para levantar hasta 40 libras.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Descripci\u00f3n del puesto: El empleado desempe\u00f1ar\u00e1 diversas funciones laborales, entre las que se incluyen las siguientes: Operador de Fresadora CNC o Torno o Gundrill Operador&#8230;<\/p>\n","protected":false},"author":2,"template":"","meta":{"_monsterinsights_skip_tracking":false},"class_list":{"0":"post-3720","1":"awsm_job_openings","2":"type-awsm_job_openings","3":"status-publish","5":"job-category-maquinista-cnc","6":"job-type-a-tiempo-completo","7":"job-location-moldes-de-primera-calidad"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Maquinista CNC - Top Grade Molds<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maquinista CNC - Top Grade Molds\" \/>\n<meta property=\"og:description\" content=\"Descripci\u00f3n del puesto: El empleado desempe\u00f1ar\u00e1 diversas funciones laborales, entre las que se incluyen las siguientes: Operador de Fresadora CNC o Torno o Gundrill Operador...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/\" \/>\n<meta property=\"og:site_name\" content=\"Top Grade Molds\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TopGradeMolds\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-21T18:37:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/topgrademolds.com\/wp-content\/uploads\/2024\/05\/TG-Logo.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"672\" \/>\n\t<meta property=\"og:image:height\" content=\"208\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/\",\"url\":\"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/\",\"name\":\"Maquinista CNC - Top Grade Molds\",\"isPartOf\":{\"@id\":\"https:\/\/topgrademolds.com\/es\/#website\"},\"datePublished\":\"2024-03-28T13:43:09+00:00\",\"dateModified\":\"2024-08-21T18:37:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/topgrademolds.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ofertas de empleo\",\"item\":\"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maquinista CNC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/topgrademolds.com\/es\/#website\",\"url\":\"https:\/\/topgrademolds.com\/es\/\",\"name\":\"Top Grade Molds\",\"description\":\"Innovative solutions - manufactured to last\",\"publisher\":{\"@id\":\"https:\/\/topgrademolds.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/topgrademolds.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/topgrademolds.com\/es\/#organization\",\"name\":\"Top Grade Molds\",\"url\":\"https:\/\/topgrademolds.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/topgrademolds.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/topgrademolds.com\/wp-content\/uploads\/2024\/05\/TG-Logo.webp\",\"contentUrl\":\"https:\/\/topgrademolds.com\/wp-content\/uploads\/2024\/05\/TG-Logo.webp\",\"width\":672,\"height\":208,\"caption\":\"Top Grade Molds\"},\"image\":{\"@id\":\"https:\/\/topgrademolds.com\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/TopGradeMolds\/\",\"https:\/\/www.linkedin.com\/company\/top-grade-molds-ltd-\/\",\"https:\/\/www.youtube.com\/@TopGradeMolds\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maquinista CNC - Top Grade Molds","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/","og_locale":"es_ES","og_type":"article","og_title":"Maquinista CNC - Top Grade Molds","og_description":"Descripci\u00f3n del puesto: El empleado desempe\u00f1ar\u00e1 diversas funciones laborales, entre las que se incluyen las siguientes: Operador de Fresadora CNC o Torno o Gundrill Operador...","og_url":"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/","og_site_name":"Top Grade Molds","article_publisher":"https:\/\/www.facebook.com\/TopGradeMolds\/","article_modified_time":"2024-08-21T18:37:16+00:00","og_image":[{"width":672,"height":208,"url":"https:\/\/topgrademolds.com\/wp-content\/uploads\/2024\/05\/TG-Logo.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/","url":"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/","name":"Maquinista CNC - Top Grade Molds","isPartOf":{"@id":"https:\/\/topgrademolds.com\/es\/#website"},"datePublished":"2024-03-28T13:43:09+00:00","dateModified":"2024-08-21T18:37:16+00:00","breadcrumb":{"@id":"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/maquinista-cnc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/topgrademolds.com\/es\/"},{"@type":"ListItem","position":2,"name":"Ofertas de empleo","item":"https:\/\/topgrademolds.com\/es\/puestos-de-trabajo\/"},{"@type":"ListItem","position":3,"name":"Maquinista CNC"}]},{"@type":"WebSite","@id":"https:\/\/topgrademolds.com\/es\/#website","url":"https:\/\/topgrademolds.com\/es\/","name":"Top Grade Molds","description":"Innovative solutions - manufactured to last","publisher":{"@id":"https:\/\/topgrademolds.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/topgrademolds.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/topgrademolds.com\/es\/#organization","name":"Top Grade Molds","url":"https:\/\/topgrademolds.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/topgrademolds.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/topgrademolds.com\/wp-content\/uploads\/2024\/05\/TG-Logo.webp","contentUrl":"https:\/\/topgrademolds.com\/wp-content\/uploads\/2024\/05\/TG-Logo.webp","width":672,"height":208,"caption":"Top Grade Molds"},"image":{"@id":"https:\/\/topgrademolds.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TopGradeMolds\/","https:\/\/www.linkedin.com\/company\/top-grade-molds-ltd-\/","https:\/\/www.youtube.com\/@TopGradeMolds"]}]}},"_links":{"self":[{"href":"https:\/\/topgrademolds.com\/es\/wp-json\/wp\/v2\/awsm_job_openings\/3720"}],"collection":[{"href":"https:\/\/topgrademolds.com\/es\/wp-json\/wp\/v2\/awsm_job_openings"}],"about":[{"href":"https:\/\/topgrademolds.com\/es\/wp-json\/wp\/v2\/types\/awsm_job_openings"}],"author":[{"embeddable":true,"href":"https:\/\/topgrademolds.com\/es\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/topgrademolds.com\/es\/wp-json\/wp\/v2\/media?parent=3720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}